{"id":1725,"date":"2023-10-08T20:45:25","date_gmt":"2023-10-08T18:45:25","guid":{"rendered":"https:\/\/normex-werkzeuge.de\/de\/produkt\/wasserpumpenzangen-satz-crv-4-teilig-chrom-vanadium-stahl\/"},"modified":"2023-12-07T13:41:53","modified_gmt":"2023-12-07T12:41:53","slug":"wasserpumpenzangen-satz-crv-4-teilig-chrom-vanadium-stahl","status":"publish","type":"product","link":"https:\/\/normex-werkzeuge.de\/de\/produkt\/wasserpumpenzangen-satz-crv-4-teilig-chrom-vanadium-stahl\/","title":{"rendered":"Wasserpumpenzangen-Satz | 175 &#8211; 400 mm | Cr-V | 4-teilig"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>Gr\u00f6\u00dfen:<\/strong><br \/>\n175 mm \/ 250 mm \/ 300 mm \/ 400 mm<\/p>\n<p><strong>Technische Daten:<\/strong><\/p>\n<ul>\n<li>Gesenkgeschmiedet<\/li>\n<li>Mit durchgestecktem Gewerbe und Klemmschutz<\/li>\n<li>Hergestellt aus Chrom-Vanadium-Stahl<\/li>\n<li>Gefertigt nach DIN ISO 8976C<\/li>\n<li>Schwarz lackiert<\/li>\n<li>Backen und Gewerbe poliert<\/li>\n<li>Tauchisolierte Schenkel<\/li>\n<li>Sortiert in stabiler Tetron-Tasche<\/li>\n<\/ul>\n","protected":false},"featured_media":1292,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[68,28],"product_tag":[],"class_list":{"0":"post-1725","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wasserpumpenzangen","7":"product_cat-zangen","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/normex-werkzeuge.de\/de\/wp-json\/wp\/v2\/product\/1725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/normex-werkzeuge.de\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/normex-werkzeuge.de\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/normex-werkzeuge.de\/de\/wp-json\/wp\/v2\/comments?post=1725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/normex-werkzeuge.de\/de\/wp-json\/wp\/v2\/media\/1292"}],"wp:attachment":[{"href":"https:\/\/normex-werkzeuge.de\/de\/wp-json\/wp\/v2\/media?parent=1725"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/normex-werkzeuge.de\/de\/wp-json\/wp\/v2\/product_brand?post=1725"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/normex-werkzeuge.de\/de\/wp-json\/wp\/v2\/product_cat?post=1725"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/normex-werkzeuge.de\/de\/wp-json\/wp\/v2\/product_tag?post=1725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}